{"id":26744,"date":"2020-03-31T08:52:26","date_gmt":"2020-03-31T06:52:26","guid":{"rendered":"https:\/\/defibrion.com\/product\/thermometre-auriculaire-infrarouge-microlife\/"},"modified":"2025-12-03T09:53:20","modified_gmt":"2025-12-03T08:53:20","slug":"thermometre-auriculaire-infrarouge-microlife","status":"publish","type":"product","link":"https:\/\/defibrion.com\/be-fr\/produit\/thermometre-auriculaire-infrarouge-microlife\/","title":{"rendered":"Thermom\u00e8tre auriculaire infrarouge Microlife"},"content":{"rendered":"<p>Ce thermom\u00e8tre auriculaire num\u00e9rique affiche votre temp\u00e9rature en 1 seconde seulement. Celui-ci mesure votre temp\u00e9rature par infrarouge, ce qui lui permet un temps d&#8217;affichage aussi rapide. Les r\u00e9sultats n&#8217;en sont pas moins pr\u00e9cis et fiables. La prise de temp\u00e9rature n&#8217;est donc pas g\u00eanante. Le thermom\u00e8tre est muni d&#8217;une alarme int\u00e9gr\u00e9e qui se d\u00e9clenche d\u00e8s que la temp\u00e9rature d\u00e9passe les 37.5\u00b0C et l&#8217;affichage passe alors au rouge.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce thermom\u00e8tre auriculaire num\u00e9rique affiche votre temp\u00e9rature en 1 seconde seulement. Celui-ci mesure votre temp\u00e9rature par infrarouge, ce qui lui permet un temps d&#8217;affichage aussi rapide. Les r\u00e9sultats n&#8217;en sont pas moins pr\u00e9cis et fiables. La prise de temp\u00e9rature n&#8217;est donc pas g\u00eanante. Le thermom\u00e8tre est muni d&#8217;une alarme int\u00e9gr\u00e9e qui se d\u00e9clenche d\u00e8s que la temp\u00e9rature d\u00e9passe les 37.5\u00b0C et l&#8217;affichage passe alors au rouge.<\/p>\n<p><strong>Ce produit est pas en stock<\/strong><\/p>\n","protected":false},"featured_media":122645,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[1065,2386,2391],"product_tag":[],"class_list":["post-26744","product","type-product","status-publish","has-post-thumbnail","product_cat-gamme-de-premiers-secours","product_cat-kits-de-premiers-secours","product_cat-trousse-de-premiers-secours-autre","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"composite_virtual":false,"composite_layout":"","composite_add_to_cart_form_location":"","composite_editable_in_cart":false,"composite_sold_individually_context":"","composite_shop_price_calc":"","composite_components":[],"composite_scenarios":[],"bundled_by":[],"bundle_stock_status":"outofstock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"_links":{"self":[{"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/product\/26744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/comments?post=26744"}],"version-history":[{"count":2,"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/product\/26744\/revisions"}],"predecessor-version":[{"id":135497,"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/product\/26744\/revisions\/135497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/media\/122645"}],"wp:attachment":[{"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/media?parent=26744"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/product_brand?post=26744"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/product_cat?post=26744"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/defibrion.com\/be-fr\/wp-json\/wp\/v2\/product_tag?post=26744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}